{"id":10304,"date":"2022-03-14T11:58:54","date_gmt":"2022-03-14T10:58:54","guid":{"rendered":"https:\/\/logos-golf.it\/site\/?p=10304"},"modified":"2024-05-07T18:57:03","modified_gmt":"2024-05-07T16:57:03","slug":"decalogo-etichetta-logos","status":"publish","type":"post","link":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/","title":{"rendered":"Decalogo Etichetta LOGOS"},"content":{"rendered":"<h1 id=\"panel-9199-0-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child\" style=\"text-align: center;\" data-index=\"0\" data-style=\"{&quot;background_image_attachment&quot;:false,&quot;background_display&quot;:&quot;tile&quot;,&quot;background_image_size&quot;:&quot;full&quot;,&quot;border_thickness&quot;:&quot;1px&quot;}\"><span style=\"color: #bc4b00; font-size: 36pt;\">DECALOGO DEL GOLFISTA LOGOS<\/span><\/h1>\n<div id=\"panel-9199-0-0-1\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"1\" data-style=\"{&quot;background_image_attachment&quot;:false,&quot;background_display&quot;:&quot;tile&quot;,&quot;background_image_size&quot;:&quot;full&quot;,&quot;border_thickness&quot;:&quot;1px&quot;}\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<ol>\n<li><span style=\"font-size: 14pt;\">Non perdere tempo nel giocare le buche e non farne perdere agli altri; eccetto che sul putting-green, chi \u00e8 pronto pu\u00f2 giocare anche se pi\u00f9 vicino alla buca, purch\u00e9 in sicurezza e non contemporaneamente ad un compagno di partita.<\/span><\/li>\n<li><span style=\"font-size: 14pt; color: #ff0000;\">Al proprio turno, farsi trovare pronti, con il guanto calzato, avendo gi\u00e0 idea della distanza e del bastone da giocare.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Avere un abbigliamento adeguato e tenere un comportamento rispettoso verso il campo e gli altri giocatori; non lasciare sul campo rifiuti o mozziconi di sigarette; evitare discussioni, litigi o peggio, imprecazioni o espressioni blasfeme;<\/span><\/li>\n<li><span style=\"font-size: 14pt; color: #ff0000;\">Comunicare le disdette al gioco, sempre ed in tempo utile, specialmente quando si partecipa alle gare.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Presentarsi alla partenza con puntualit\u00e0.<\/span><\/li>\n<li><span style=\"font-size: 14pt; color: #ff0000;\">Cedere il passo ai gruppi pi\u00f9 veloci; NOTA BENE: il giocatore singolo \u00e8 da considerarsi &#8220;gruppo&#8221;.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Predisporre il carrello e\/o la sacca all&#8217;uscita del putting-green verso la buca successiva e liberare il putting-green prima possibile; annotare lo score sul tee della buca seguente.<\/span><\/li>\n<li><span style=\"font-size: 14pt; color: #ff0000;\">Evitare rumori o dialoghi, e non fare movimenti quando un altro giocatore si accinga ad effettuare un colpo.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Non cercare la palla oltre i 3 minuti dopo l&#8217;arrivo nel punto presunto di atterraggio; qualora il ritrovamento si preveda difficoltoso, cedere il passo al gruppo seguente eventualmente in attesa.<\/span><\/li>\n<li><span style=\"font-size: 14pt; color: #ff0000;\">Avere cura del percorso, livellando accuratamente i bunkers, ripiazzando le zolle e riparando i pitchmarks, non soltanto i propri; se si dispone di un golf-cart, muoversi possibilmente in rough o percorrere le apposite stradine ove presenti.<\/span><\/li>\n<\/ol>\n<h3 style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><strong>oltre all&#8217;etichetta, osserviamo bene il motto del Golf Club pi\u00f9 antico del mondo<\/strong><\/span><\/h3>\n<p><span style=\"font-size: 14pt;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9200 aligncenter\" src=\"https:\/\/logos-golf.it\/site\/wp-content\/uploads\/2022\/12\/musselbrough-251x300.png\" alt=\"\" width=\"251\" height=\"300\" srcset=\"https:\/\/logos-golf.it\/site\/wp-content\/uploads\/2022\/12\/musselbrough-251x300.png 251w, https:\/\/logos-golf.it\/site\/wp-content\/uploads\/2022\/12\/musselbrough.png 600w\" sizes=\"auto, (max-width: 251px) 100vw, 251px\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><em>Musselbrough Old Course &#8211; The World&#8217;s Oldest Golf Course 1567<\/em><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>DECALOGO DEL GOLFISTA LOGOS Non perdere tempo nel giocare le buche e non farne perdere agli altri; eccetto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-10304","post","type-post","status-publish","format-standard","hentry","category-regole-etichetta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Decalogo Etichetta LOGOS - Libera Organizzazione Golfisti Seniores<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Decalogo Etichetta LOGOS - Libera Organizzazione Golfisti Seniores\" \/>\r\n<meta property=\"og:description\" content=\"DECALOGO DEL GOLFISTA LOGOS Non perdere tempo nel giocare le buche e non farne perdere agli altri; eccetto [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Libera Organizzazione Golfisti Seniores\" \/>\r\n<meta property=\"article:published_time\" content=\"2022-03-14T10:58:54+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-05-07T16:57:03+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/logos-golf.it\/site\/wp-content\/uploads\/2022\/12\/musselbrough-251x300.png\" \/>\r\n<meta name=\"author\" content=\"LogosBruno_SITE\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"LogosBruno_SITE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/2022\\\/03\\\/14\\\/decalogo-etichetta-logos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/2022\\\/03\\\/14\\\/decalogo-etichetta-logos\\\/\"},\"author\":{\"name\":\"LogosBruno_SITE\",\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/#\\\/schema\\\/person\\\/43dc24f0e8987f20f00127946439f1c1\"},\"headline\":\"Decalogo Etichetta LOGOS\",\"datePublished\":\"2022-03-14T10:58:54+00:00\",\"dateModified\":\"2024-05-07T16:57:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/2022\\\/03\\\/14\\\/decalogo-etichetta-logos\\\/\"},\"wordCount\":272,\"publisher\":{\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/2022\\\/03\\\/14\\\/decalogo-etichetta-logos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/musselbrough-251x300.png\",\"articleSection\":[\"Regole &amp; Etichetta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/2022\\\/03\\\/14\\\/decalogo-etichetta-logos\\\/\",\"url\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/2022\\\/03\\\/14\\\/decalogo-etichetta-logos\\\/\",\"name\":\"Decalogo Etichetta LOGOS - Libera Organizzazione Golfisti Seniores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/2022\\\/03\\\/14\\\/decalogo-etichetta-logos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/2022\\\/03\\\/14\\\/decalogo-etichetta-logos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/musselbrough-251x300.png\",\"datePublished\":\"2022-03-14T10:58:54+00:00\",\"dateModified\":\"2024-05-07T16:57:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/2022\\\/03\\\/14\\\/decalogo-etichetta-logos\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/logos-golf.it\\\/site\\\/2022\\\/03\\\/14\\\/decalogo-etichetta-logos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/2022\\\/03\\\/14\\\/decalogo-etichetta-logos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/musselbrough.png\",\"contentUrl\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/musselbrough.png\",\"width\":600,\"height\":716},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/2022\\\/03\\\/14\\\/decalogo-etichetta-logos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decalogo Etichetta LOGOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/\",\"name\":\"Logos - Libera Organizzazione Golfisti Seniores\",\"description\":\"agonismo e convivialit\u00e0\",\"publisher\":{\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/#organization\",\"name\":\"Logos - Libera Organizzazione Golfisti Seniores\",\"url\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Logo-Logos-bellogrande-ROSSO.png\",\"contentUrl\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Logo-Logos-bellogrande-ROSSO.png\",\"width\":1024,\"height\":341,\"caption\":\"Logos - Libera Organizzazione Golfisti Seniores\"},\"image\":{\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/logos-golf.it\\\/site\\\/#\\\/schema\\\/person\\\/43dc24f0e8987f20f00127946439f1c1\",\"name\":\"LogosBruno_SITE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc69f2098b0f523228b76c86e8278d59ca3e16f9586865243f22c7bcf332e260?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc69f2098b0f523228b76c86e8278d59ca3e16f9586865243f22c7bcf332e260?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc69f2098b0f523228b76c86e8278d59ca3e16f9586865243f22c7bcf332e260?s=96&d=mm&r=g\",\"caption\":\"LogosBruno_SITE\"},\"sameAs\":[\"https:\\\/\\\/logos-golf.it\\\/site\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Decalogo Etichetta LOGOS - Libera Organizzazione Golfisti Seniores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/","og_locale":"it_IT","og_type":"article","og_title":"Decalogo Etichetta LOGOS - Libera Organizzazione Golfisti Seniores","og_description":"DECALOGO DEL GOLFISTA LOGOS Non perdere tempo nel giocare le buche e non farne perdere agli altri; eccetto [&hellip;]","og_url":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/","og_site_name":"Libera Organizzazione Golfisti Seniores","article_published_time":"2022-03-14T10:58:54+00:00","article_modified_time":"2024-05-07T16:57:03+00:00","og_image":[{"url":"https:\/\/logos-golf.it\/site\/wp-content\/uploads\/2022\/12\/musselbrough-251x300.png","type":"","width":"","height":""}],"author":"LogosBruno_SITE","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"LogosBruno_SITE","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/#article","isPartOf":{"@id":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/"},"author":{"name":"LogosBruno_SITE","@id":"https:\/\/logos-golf.it\/site\/#\/schema\/person\/43dc24f0e8987f20f00127946439f1c1"},"headline":"Decalogo Etichetta LOGOS","datePublished":"2022-03-14T10:58:54+00:00","dateModified":"2024-05-07T16:57:03+00:00","mainEntityOfPage":{"@id":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/"},"wordCount":272,"publisher":{"@id":"https:\/\/logos-golf.it\/site\/#organization"},"image":{"@id":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/#primaryimage"},"thumbnailUrl":"https:\/\/logos-golf.it\/site\/wp-content\/uploads\/2022\/12\/musselbrough-251x300.png","articleSection":["Regole &amp; Etichetta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/","url":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/","name":"Decalogo Etichetta LOGOS - Libera Organizzazione Golfisti Seniores","isPartOf":{"@id":"https:\/\/logos-golf.it\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/#primaryimage"},"image":{"@id":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/#primaryimage"},"thumbnailUrl":"https:\/\/logos-golf.it\/site\/wp-content\/uploads\/2022\/12\/musselbrough-251x300.png","datePublished":"2022-03-14T10:58:54+00:00","dateModified":"2024-05-07T16:57:03+00:00","breadcrumb":{"@id":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/#primaryimage","url":"https:\/\/logos-golf.it\/site\/wp-content\/uploads\/2022\/12\/musselbrough.png","contentUrl":"https:\/\/logos-golf.it\/site\/wp-content\/uploads\/2022\/12\/musselbrough.png","width":600,"height":716},{"@type":"BreadcrumbList","@id":"https:\/\/logos-golf.it\/site\/2022\/03\/14\/decalogo-etichetta-logos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/logos-golf.it\/site\/"},{"@type":"ListItem","position":2,"name":"Decalogo Etichetta LOGOS"}]},{"@type":"WebSite","@id":"https:\/\/logos-golf.it\/site\/#website","url":"https:\/\/logos-golf.it\/site\/","name":"Logos - Libera Organizzazione Golfisti Seniores","description":"agonismo e convivialit\u00e0","publisher":{"@id":"https:\/\/logos-golf.it\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/logos-golf.it\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/logos-golf.it\/site\/#organization","name":"Logos - Libera Organizzazione Golfisti Seniores","url":"https:\/\/logos-golf.it\/site\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/logos-golf.it\/site\/#\/schema\/logo\/image\/","url":"https:\/\/logos-golf.it\/site\/wp-content\/uploads\/2023\/01\/Logo-Logos-bellogrande-ROSSO.png","contentUrl":"https:\/\/logos-golf.it\/site\/wp-content\/uploads\/2023\/01\/Logo-Logos-bellogrande-ROSSO.png","width":1024,"height":341,"caption":"Logos - Libera Organizzazione Golfisti Seniores"},"image":{"@id":"https:\/\/logos-golf.it\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/logos-golf.it\/site\/#\/schema\/person\/43dc24f0e8987f20f00127946439f1c1","name":"LogosBruno_SITE","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dc69f2098b0f523228b76c86e8278d59ca3e16f9586865243f22c7bcf332e260?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc69f2098b0f523228b76c86e8278d59ca3e16f9586865243f22c7bcf332e260?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc69f2098b0f523228b76c86e8278d59ca3e16f9586865243f22c7bcf332e260?s=96&d=mm&r=g","caption":"LogosBruno_SITE"},"sameAs":["https:\/\/logos-golf.it\/site"]}]}},"_links":{"self":[{"href":"https:\/\/logos-golf.it\/site\/wp-json\/wp\/v2\/posts\/10304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/logos-golf.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/logos-golf.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/logos-golf.it\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/logos-golf.it\/site\/wp-json\/wp\/v2\/comments?post=10304"}],"version-history":[{"count":6,"href":"https:\/\/logos-golf.it\/site\/wp-json\/wp\/v2\/posts\/10304\/revisions"}],"predecessor-version":[{"id":13950,"href":"https:\/\/logos-golf.it\/site\/wp-json\/wp\/v2\/posts\/10304\/revisions\/13950"}],"wp:attachment":[{"href":"https:\/\/logos-golf.it\/site\/wp-json\/wp\/v2\/media?parent=10304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/logos-golf.it\/site\/wp-json\/wp\/v2\/categories?post=10304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/logos-golf.it\/site\/wp-json\/wp\/v2\/tags?post=10304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}